{"id":17602,"date":"2020-05-01T16:14:53","date_gmt":"2020-05-01T19:14:53","guid":{"rendered":"http:\/\/www.polisrecreio.com.br\/site\/?p=17602"},"modified":"2020-05-01T16:14:53","modified_gmt":"2020-05-01T19:14:53","slug":"camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio","status":"publish","type":"post","link":"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/","title":{"rendered":"C\u00e2mara Municipal vai votar nesta sexta-feira (1) o projeto de combate ao coronav\u00edrus em Recreio"},"content":{"rendered":"<p style=\"text-align: justify;\">A C\u00e2mara Municipal vai votar nesta sexta-feira (1), \u00e0s 17h, o projeto de lei de autoria do executivo que solicita autoriza\u00e7\u00e3o para abertura de cr\u00e9dito especial de R$ 110 mil (recurso federal) para a\u00e7\u00f5es de combate ao coronav\u00edrus. O documento deveria ter sido votado na \u00faltima ter\u00e7a-feira (28).<\/p>\n<p><!--more--><\/p>\n<figure id=\"attachment_17561\" aria-describedby=\"caption-attachment-17561\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014.jpg\"><img loading=\"lazy\" class=\"wp-image-17561 size-full\" src=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014.jpg 750w, https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-17561\" class=\"wp-caption-text\">Sess\u00e3o da C\u00e2mara do dia 28\/03.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Na sess\u00e3o de ter\u00e7a-feira a vota\u00e7\u00e3o n\u00e3o aconteceu por causa de um pedido de vista da vereadora Leninha (Patriotas) e foi remarcada para a \u00faltima quinta-feira (30), por\u00e9m, de forma abrupta, o presidente da C\u00e2mara, Chiquinho, encerrou a reuni\u00e3o sem que houvesse a vota\u00e7\u00e3o do PL.<\/p>\n<p style=\"text-align: justify;\">O motivo, conforme esclarecido pelo presidente, foi a aus\u00eancia da vereadora Leninha (Patriotas), que pediu vista, requereu informa\u00e7\u00f5es por meio de of\u00edcio e afastou-se do cargo por 7 dias com atestado m\u00e9dico, a partir do dia 30.<\/p>\n<p style=\"text-align: justify;\">Para esclarecer todas as d\u00favidas sobre o projeto a Prefeitura Municipal enviou o assessor cont\u00e1bil, Alexsander Lacerda de Mello Vieira. O servidor esclareceu de forma clara todos os pontos do documento, inclusive, sobre outros recursos federais que est\u00e3o dispon\u00edveis ao Munic\u00edpio para combate ao Covid-19.<\/p>\n<p style=\"text-align: justify;\">O recurso financeiro \u00e9 federal e conforme a proposta ser\u00e3o assim utilizados:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Contrata\u00e7\u00e3o por tempo determinado \u2013 R$ 30 mil;<\/li>\n<li style=\"text-align: justify;\">Material de consumo \u2013 R$ 70 mil;<\/li>\n<li style=\"text-align: justify;\">Outros servi\u00e7os de terceiros PF \u2013 R$ 5 mil;<\/li>\n<li style=\"text-align: justify;\">Outros servi\u00e7os de terceiros PJ \u2013 R$ 5 mil.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal vai votar nesta sexta-feira (1), \u00e0s 17h, o projeto de lei de autoria do executivo que solicita autoriza\u00e7\u00e3o para abertura de cr\u00e9dito especial de R$ 110 mil (recurso federal) para a\u00e7\u00f5es de combate ao coronav\u00edrus. O documento deveria ter sido votado na \u00faltima ter\u00e7a-feira (28).<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e2mara Municipal vai votar nesta sexta-feira (1) o projeto de combate ao coronav\u00edrus em Recreio - P\u00f3lis Recreio\" \/>\n<meta property=\"og:description\" content=\"A C\u00e2mara Municipal vai votar nesta sexta-feira (1), \u00e0s 17h, o projeto de lei de autoria do executivo que solicita autoriza\u00e7\u00e3o para abertura de cr\u00e9dito especial de R$ 110 mil (recurso federal) para a\u00e7\u00f5es de combate ao coronav\u00edrus. O documento deveria ter sido votado na \u00faltima ter\u00e7a-feira (28).\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00f3lis Recreio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Site-P%c3%b3lis-Recreio-MG-181941708571019\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-01T19:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:site\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/\",\"name\":\"P\\u00f3lis Recreio\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.polisrecreio.com.br\/site\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/DSC_0014.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/#webpage\",\"url\":\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/\",\"name\":\"C\\u00e2mara Municipal vai votar nesta sexta-feira (1) o projeto de combate ao coronav\\u00edrus em Recreio - P\\u00f3lis Recreio\",\"isPartOf\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/#primaryimage\"},\"datePublished\":\"2020-05-01T19:14:53+00:00\",\"dateModified\":\"2020-05-01T19:14:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.polisrecreio.com.br\/site\/2020\/05\/01\/camara-municipal-vai-votar-nesta-sexta-feira-1-o-projeto-de-combate-ao-coronavirus-em-recreio\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\",\"name\":\"Leonardo Ribeiro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ba92a37d621e1a83e23710251178a12?s=96&d=mm&r=g\",\"caption\":\"Leonardo Ribeiro\"},\"sameAs\":[\"http:\/\/www.polisrecreio.com.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17602"}],"collection":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/comments?post=17602"}],"version-history":[{"count":1,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17602\/revisions"}],"predecessor-version":[{"id":17603,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17602\/revisions\/17603"}],"wp:attachment":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/media?parent=17602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/categories?post=17602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/tags?post=17602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}