{"id":17656,"date":"2020-05-06T15:18:11","date_gmt":"2020-05-06T18:18:11","guid":{"rendered":"http:\/\/www.polisrecreio.com.br\/site\/?p=17656"},"modified":"2020-05-06T15:24:23","modified_gmt":"2020-05-06T18:24:23","slug":"aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga","status":"publish","type":"post","link":"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/","title":{"rendered":"Aumenta o n\u00famero de casos confirmados de coronav\u00edrus em Pirapetinga"},"content":{"rendered":"<p style=\"text-align: justify;\">Em Pirapetinga, segundo boletim epidemiol\u00f3gico da Prefeitura Municipal divulgado nesta quarta-feira (6), o n\u00famero de casos confirmados pelo novo coronav\u00edrus aumentou para 3.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17545\" src=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360.jpg 750w, https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Confira o boletim:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Casos suspeitos \u2013 7;<\/li>\n<li>Amostradas coletas \u2013 3;<\/li>\n<li>Aguardando resultado \u2013 3;<\/li>\n<li>Casos descartados \u2013 1;<\/li>\n<li>Casos confirmados \u2013 3.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">At\u00e9 nada no dia de ontem havia apenas 1 caso confirmado. Na cidade h\u00e1 tamb\u00e9m 1 \u00f3bito em investiga\u00e7\u00e3o. As amostras coletadas est\u00e3o em an\u00e1lise na Funda\u00e7\u00e3o Ezequiel Dias \u201cFUNED\u201d, de Belo Horizonte.<\/p>\n<p style=\"text-align: justify;\">Em Pirapetinga diversas a\u00e7\u00f5es est\u00e3o sendo tomadas pela Prefeitura Municipal no combate \u00e0 doen\u00e7a, entre elas o fechamento de com\u00e9rcios que n\u00e3o sejam extrema necessidade, barreiras sanit\u00e1rias e a obrigatoriedade do uso de m\u00e1scaras para todos que sa\u00edrem \u00e0s ruas da cidade.<\/p>\n<p><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/P.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-17657 alignleft\" src=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/P.jpg\" alt=\"\" width=\"562\" height=\"623\" srcset=\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/P.jpg 562w, https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/P-271x300.jpg 271w\" sizes=\"(max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em Pirapetinga, segundo boletim epidemiol\u00f3gico da Prefeitura Municipal divulgado nesta quarta-feira (6), o n\u00famero de casos confirmados pelo novo coronav\u00edrus aumentou para 3.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumenta o n\u00famero de casos confirmados de coronav\u00edrus em Pirapetinga - P\u00f3lis Recreio\" \/>\n<meta property=\"og:description\" content=\"Em Pirapetinga, segundo boletim epidemiol\u00f3gico da Prefeitura Municipal divulgado nesta quarta-feira (6), o n\u00famero de casos confirmados pelo novo coronav\u00edrus aumentou para 3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00f3lis Recreio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Site-P%c3%b3lis-Recreio-MG-181941708571019\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T18:18:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-06T18:24:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:site\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"1 minuto\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/\",\"name\":\"P\\u00f3lis Recreio\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.polisrecreio.com.br\/site\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/04\/coronavirus-4914026_1920-640x360.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/#webpage\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/\",\"name\":\"Aumenta o n\\u00famero de casos confirmados de coronav\\u00edrus em Pirapetinga - P\\u00f3lis Recreio\",\"isPartOf\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/#primaryimage\"},\"datePublished\":\"2020-05-06T18:18:11+00:00\",\"dateModified\":\"2020-05-06T18:24:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/06\/aumenta-o-numero-de-casos-confirmados-de-coronavirus-em-pirapetinga\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\",\"name\":\"Leonardo Ribeiro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ba92a37d621e1a83e23710251178a12?s=96&d=mm&r=g\",\"caption\":\"Leonardo Ribeiro\"},\"sameAs\":[\"http:\/\/www.polisrecreio.com.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17656"}],"collection":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/comments?post=17656"}],"version-history":[{"count":4,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17656\/revisions"}],"predecessor-version":[{"id":17661,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17656\/revisions\/17661"}],"wp:attachment":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/media?parent=17656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/categories?post=17656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/tags?post=17656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}