{"id":17775,"date":"2020-05-14T18:44:33","date_gmt":"2020-05-14T21:44:33","guid":{"rendered":"http:\/\/www.polisrecreio.com.br\/site\/?p=17775"},"modified":"2020-05-14T18:54:55","modified_gmt":"2020-05-14T21:54:55","slug":"sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm","status":"publish","type":"post","link":"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/","title":{"rendered":"Sem ajuda federal, prefeituras n\u00e3o ter\u00e3o condi\u00e7\u00f5es de pagar sal\u00e1rios dos servidores, diz AMM"},"content":{"rendered":"<p style=\"text-align: justify;\">As prefeituras de Minas Gerais come\u00e7aram o ano de 2020 com um alento para ajudar nas finan\u00e7as: o Governo do Estado iniciava o cumprimento do acordo para regularizar a d\u00edvida de ICMS, IPVA e outros, com as administra\u00e7\u00f5es das 853 cidades. Por\u00e9m, de repente, surgiu a pandemia do novo coronav\u00edrus e aquele in\u00edcio de boas expectativas passou para o desenvolvimento de um caos econ\u00f4mico que n\u00e3o h\u00e1 previs\u00e3o de chegar ao fim. A Associa\u00e7\u00e3o Mineira de Munic\u00edpios \u201cAMM\u201d informou que caso n\u00e3o haja a ajuda financeira federal em maio, muitas prefeituras j\u00e1 n\u00e3o ter\u00e3o condi\u00e7\u00f5es de pagar os sal\u00e1rios de seus servidores por causa da forte queda de receitas (FPM, ISS, ICMS e outros) devido a paralisa\u00e7\u00e3o de atividades econ\u00f4micas.<\/p>\n<p><!--more--><\/p>\n<p><a href=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\u00e7\u00e3o-Sefaz.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-17776\" src=\"http:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\u00e7\u00e3o-Sefaz.jpg\" alt=\"\" width=\"750\" height=\"441\" srcset=\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\u00e7\u00e3o-Sefaz.jpg 750w, https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\u00e7\u00e3o-Sefaz-300x176.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Em mat\u00e9ria do jornal O Tempo desta quinta-feira (14), o presidente da Associa\u00e7\u00e3o Mineira de Munic\u00edpios (AMM), 1\u00ba vice-presidente da Confedera\u00e7\u00e3o Nacional de Munic\u00edpios (CNM) e prefeito de Moema, Julvan Lacerda, destaca que, apesar da Medida Provis\u00f3ria que recomp\u00f5e o FPM e do PLP 39\/2020 (o texto ainda aguarda san\u00e7\u00e3o presidencial), os valores de compensa\u00e7\u00e3o das perdas dos munic\u00edpios representam apenas um ter\u00e7o em rela\u00e7\u00e3o aos valores do mesmo m\u00eas no ano passado.<\/p>\n<p style=\"text-align: justify;\">O presidente destaca que a AMM reconhece o empenho do Congresso Nacional, que possibilitou a aprecia\u00e7\u00e3o e aprova\u00e7\u00e3o do PLP 39\/2020, mas que \u201co recurso a ser enviado aos munic\u00edpios \u00e9 bem menor do que as perdas. Ele representa apenas um ter\u00e7o dessa impactante queda de receita em todos os munic\u00edpios com reflexo imediato no atendimento \u00e0 popula\u00e7\u00e3o. Ou seja, teremos uma queda de R$ 74 bilh\u00f5es de receita e o repasse federal ser\u00e1 de R$ 23 bilh\u00f5es\u201d.<\/p>\n<p style=\"text-align: justify;\">Os efeitos do isolamento social e da queda na economia dos munic\u00edpios come\u00e7a a ser sentido pelas administra\u00e7\u00f5es municipais com mais for\u00e7a no m\u00eas de maio. Prefeitos de diferentes regi\u00f5es do estado ressaltam que al\u00e9m da queda nos repasses, tamb\u00e9m est\u00e1 havendo queda na receita dos impostos e taxas municipais, como o Imposto Predial e Territorial Urbano (IPTU) e o ISS, que tiveram prazos de vencimento adiados ou arrecada\u00e7\u00e3o baixa.<\/p>\n<p style=\"text-align: justify;\">Em Recreio, at\u00e9 o momento, os servidores municipais est\u00e3o com seus sal\u00e1rios em dia. Os vencimentos referentes ao m\u00eas trabalhado de abril foram quitados antes do dia 1\u00ba de maio. A Prefeitura est\u00e1 na expectativa de receber por meio do PLP 39\/2020, R$ 1.157.582,57, recursos que dever\u00e3o ser investidos uma parte em pol\u00edticas p\u00fablicas de enfrentamento ao coronav\u00edrus e outra em a\u00e7\u00f5es livres.<\/p>\n<p style=\"text-align: justify;\"><em>Leia:\u00a0<a href=\"https:\/\/portalamm.org.br\/o-tempo-julvan-lacerda-destaca-que-ajuda-federal-nao-cobre-um-terco-das-perdas-dos-municipios-na-pandemia-do-coronavirus\/\" target=\"_blank\" rel=\"noopener\">https:\/\/portalamm.org.br\/o-tempo-julvan-lacerda-destaca-que-ajuda-federal-nao-cobre-um-terco-das-perdas-dos-municipios-na-pandemia-do-coronavirus\/<\/a><\/em><\/p>\n<p style=\"text-align: justify;\"><em>Leia:\u00a0<a href=\"https:\/\/www.otempo.com.br\/politica\/com-pandemia-municipios-mineiros-perdem-mais-de-um-terco-dos-repasses-1.2336772\" target=\"_blank\" rel=\"noopener\">https:\/\/www.otempo.com.br\/politica\/com-pandemia-municipios-mineiros-perdem-mais-de-um-terco-dos-repasses-1.2336772<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As prefeituras de Minas Gerais come\u00e7aram o ano de 2020 com um alento para ajudar nas finan\u00e7as: o Governo do Estado iniciava o cumprimento do acordo para regularizar a d\u00edvida de ICMS, IPVA e outros, com as administra\u00e7\u00f5es das 853 cidades. Por\u00e9m, de repente, surgiu a pandemia do novo coronav\u00edrus e aquele in\u00edcio de boas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17776,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sem ajuda federal, prefeituras n\u00e3o ter\u00e3o condi\u00e7\u00f5es de pagar sal\u00e1rios dos servidores, diz AMM - P\u00f3lis Recreio\" \/>\n<meta property=\"og:description\" content=\"As prefeituras de Minas Gerais come\u00e7aram o ano de 2020 com um alento para ajudar nas finan\u00e7as: o Governo do Estado iniciava o cumprimento do acordo para regularizar a d\u00edvida de ICMS, IPVA e outros, com as administra\u00e7\u00f5es das 853 cidades. Por\u00e9m, de repente, surgiu a pandemia do novo coronav\u00edrus e aquele in\u00edcio de boas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u00f3lis Recreio\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Site-P%c3%b3lis-Recreio-MG-181941708571019\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T21:44:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-14T21:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\u00e7\u00e3o-Sefaz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"441\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:site\" content=\"@PolisRecreio\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data1\" content=\"2 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/\",\"name\":\"P\\u00f3lis Recreio\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.polisrecreio.com.br\/site\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/wp-content\/uploads\/2020\/05\/recupera\\u00e7\\u00e3o-Sefaz.jpg\",\"width\":750,\"height\":441},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/#webpage\",\"url\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/\",\"name\":\"Sem ajuda federal, prefeituras n\\u00e3o ter\\u00e3o condi\\u00e7\\u00f5es de pagar sal\\u00e1rios dos servidores, diz AMM - P\\u00f3lis Recreio\",\"isPartOf\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/#primaryimage\"},\"datePublished\":\"2020-05-14T21:44:33+00:00\",\"dateModified\":\"2020-05-14T21:54:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.polisrecreio.com.br\/site\/2020\/05\/14\/sem-ajuda-federal-prefeituras-nao-terao-condicoes-de-pagar-salarios-dos-servidores-diz-amm\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#\/schema\/person\/3363c1c78e1e28e1329d97adb387638e\",\"name\":\"Leonardo Ribeiro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.polisrecreio.com.br\/site\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6ba92a37d621e1a83e23710251178a12?s=96&d=mm&r=g\",\"caption\":\"Leonardo Ribeiro\"},\"sameAs\":[\"http:\/\/www.polisrecreio.com.br\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17775"}],"collection":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/comments?post=17775"}],"version-history":[{"count":6,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17775\/revisions"}],"predecessor-version":[{"id":17782,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/posts\/17775\/revisions\/17782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/media\/17776"}],"wp:attachment":[{"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/media?parent=17775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/categories?post=17775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polisrecreio.com.br\/site\/wp-json\/wp\/v2\/tags?post=17775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}